{"id":59,"count":10,"description":"","link":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/","name":"KMI Interdisciplinary Seminar","slug":"kmi-interdisciplinary-seminar","taxonomy":"seminar_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/\" \/>\n<meta property=\"og:site_name\" content=\"KMI - Nagoya University\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/seminar\\\/seminar_category\\\/kmi-interdisciplinary-seminar\\\/\",\"url\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/seminar\\\/seminar_category\\\/kmi-interdisciplinary-seminar\\\/\",\"name\":\"KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/seminar\\\/seminar_category\\\/kmi-interdisciplinary-seminar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/seminar\\\/seminar_category\\\/kmi-interdisciplinary-seminar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KMI Interdisciplinary Seminar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/\",\"name\":\"KMI - Nagoya University\",\"description\":\"Nagoya University: Kobayashi-Maskawa Institute for the Origin of Particles and the Universe (KMI)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kmi.nagoya-u.ac.jp\\\/eng\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/","og_locale":"en_US","og_type":"article","og_title":"KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University","og_url":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/","og_site_name":"KMI - Nagoya University","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/","url":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/","name":"KMI Interdisciplinary Seminar \u30a2\u30fc\u30ab\u30a4\u30d6 - KMI - Nagoya University","isPartOf":{"@id":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/seminar\/seminar_category\/kmi-interdisciplinary-seminar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/"},{"@type":"ListItem","position":2,"name":"KMI Interdisciplinary Seminar"}]},{"@type":"WebSite","@id":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/#website","url":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/","name":"KMI - Nagoya University","description":"Nagoya University: Kobayashi-Maskawa Institute for the Origin of Particles and the Universe (KMI)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/wp-json\/wp\/v2\/seminar_category\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/wp-json\/wp\/v2\/seminar_category"}],"about":[{"href":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/wp-json\/wp\/v2\/taxonomies\/seminar_category"}],"wp:post_type":[{"href":"https:\/\/www.kmi.nagoya-u.ac.jp\/eng\/wp-json\/wp\/v2\/seminar?seminar_category=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}